{"id":11075,"date":"2022-02-07T09:00:00","date_gmt":"2022-02-07T00:00:00","guid":{"rendered":"https:\/\/engoo.co.kr\/blog\/?p=11075"},"modified":"2022-08-05T10:43:57","modified_gmt":"2022-08-05T01:43:57","slug":"%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb","status":"publish","type":"post","link":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/","title":{"rendered":"\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b)"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192308\/0-2.jpg\" alt=\"\" class=\"wp-image-11076\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192308\/0-2.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192308\/0-2-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192308\/0-2-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192308\/0-2-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p>\uc548\ub155\ud558\uc138\uc694. <strong>\uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4<\/strong>\uc785\ub2c8\ub2e4.<\/p>\n\n\n\n<p>\u2018<strong>\ub290\ub08c\ud45c<\/strong>\u2019\ub294 \uc601\uc5b4\ub85c \uc5b4\ub5bb\uac8c \ub9d0\ud560\uae4c\uc694? \uc624\ub298\uc740 \uac01\uc885 <strong>\ud2b9\uc218\ubb38\uc790(!?&amp;\u203b\/)<\/strong> \ub97c \uc601\uc5b4\ub85c \uc5b4\ub5bb\uac8c \ud45c\ud604\ud558\ub294\uc9c0 \ud568\uaed8 \uc54c\uc544\ubcf4\ub3c4\ub85d \ud558\uaca0\uc2b5\ub2c8\ub2e4!<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192320\/1-1.jpg\" alt=\"\" class=\"wp-image-11077\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192320\/1-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192320\/1-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192320\/1-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192320\/1-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffda76\"><strong>period \/ full stop\u00a0: . (\ub9c8\uce68\ud45c\/\uc628\uc810)<\/strong><\/p>\n\n\n\n<p><strong>period<\/strong>\ub294 \uc5b4\ub5a4 \uc77c\uc774\ub098 \uc0ac\uac74\uc758 \ub9c8\uc9c0\ub9c9\uc744 \uc758\ubbf8\ud558\uae30 \ub54c\ubb38\uc5d0 \ubb38\uc7a5\uc744 \ub05d\ub0b4\ub294 <strong>\ub9c8\uce68\ud45c<\/strong>\ub97c period\ub77c\uace0 \ud569\ub2c8\ub2e4.<br>\ube44\uc2b7\ud558\uac8c \uc644\uc804\ud55c \ub05d\uc774\ub77c\ub294 \ub73b\uc758 <strong>full stop<\/strong>\ub3c4 \ub9c8\uce68\ud45c\ub77c\ub294 \uc758\ubbf8\ub97c \uac16\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192327\/2-1.jpg\" alt=\"\" class=\"wp-image-11078\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192327\/2-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192327\/2-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192327\/2-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192327\/2-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p><em>You must put a period(full stop) at the end of the sentence.<br>\ubb38\uc7a5\uc758 \ub05d\ubd80\ubd84\uc5d0\ub294 \uaf2d \ub9c8\uce68\ud45c\ub97c \ucc0d\uc5b4\uc57c \ud55c\ub2e4.<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192334\/3-1.jpg\" alt=\"\" class=\"wp-image-11079\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192334\/3-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192334\/3-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192334\/3-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192334\/3-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffda76\"><strong>exclamation mark<\/strong> : <strong>! (\ub290\ub08c\ud45c)<\/strong><\/p>\n\n\n\n<p><strong>exclaim<\/strong>\uc740 '\ud070 \uc18c\ub9ac\ub85c \uc678\uce58\ub2e4'\ub77c\ub294 \ub73b\uc774\uba70, <strong>exclamation<\/strong>\uc740 '\uac10\ud0c4\uc0ac'\ub77c\ub294 \ub73b\uc785\ub2c8\ub2e4.<br>\ub530\ub77c\uc11c \uc774\ub7ec\ud55c \uac10\ud0c4\uc744 \ud45c\ud604\ud558\ub294 \ub290\ub08c\ud45c\ub97c <strong>exclamation mark<\/strong>\ub77c\uace0 \ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192341\/4-1.jpg\" alt=\"\" class=\"wp-image-11080\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192341\/4-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192341\/4-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192341\/4-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192341\/4-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p><em>Exclamation marks are used to express excessive emotions.<br>\ub290\ub08c\ud45c\ub294 \uaca9\ud55c \uac10\uc815\ub4e4\uc744 \ud45c\ud604\ud560 \ub54c \uc4f0\uc778\ub2e4.<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192348\/5-1.jpg\" alt=\"\" class=\"wp-image-11081\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192348\/5-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192348\/5-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192348\/5-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192348\/5-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffda76\"><strong>question mark\u00a0: ? (\ubb3c\uc74c\ud45c)<\/strong><\/p>\n\n\n\n<p>\uc9c8\ubb38\uc774\ub098 \uc758\ubb38\uc744 \ub73b\ud558\ub294 <strong>question<\/strong>\uc774 \ubb3c\uc74c\ud45c, <strong>question mark<\/strong>\ub97c \ub73b\ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192355\/6-1.jpg\" alt=\"\" class=\"wp-image-11082\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192355\/6-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192355\/6-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192355\/6-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192355\/6-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p><em>It is effective to start essays with a question mark.<br>\uc5d0\uc138\uc774\ub294 \ubb3c\uc74c\ud45c\ub85c \uc2dc\uc791\ud558\ub294 \uac8c \ud6a8\uc728\uc801\uc774\ub2e4.<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192403\/7-1.jpg\" alt=\"\" class=\"wp-image-11083\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192403\/7-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192403\/7-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192403\/7-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192403\/7-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffda76\"><strong>parenthesis \/ bracket<\/strong> : <strong>() (\uad04\ud638<\/strong>)<\/p>\n\n\n\n<p>\ubb38\ub9e5\uc758 \uc138\ubd80\uc801\uc778 \ub0b4\uc6a9\uc744 \ucd94\uac00\ud560 \ub54c, <strong>parenthesis<\/strong> \ub610\ub294 <strong>bracket<\/strong>\uc744 \uc0ac\uc6a9\ud569\ub2c8\ub2e4.<br>[ ]\ub294 <strong>square bracket<\/strong>\uc774\ub77c\uace0 \ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192409\/8-1.jpg\" alt=\"\" class=\"wp-image-11084\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192409\/8-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192409\/8-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192409\/8-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192409\/8-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p><em>Parentheses separate data that is not vital to the sentence.<br>\uad04\ud638\ub294 \ud06c\uac8c \uc911\uc694\ud558\uc9c0 \uc54a\uc740 \ub0b4\uc6a9\uc744 \ubb38\uc7a5\uc5d0\uc11c \ubd84\ub9ac\ud560 \ub54c \uc0ac\uc6a9\ud55c\ub2e4.<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192418\/9-1.jpg\" alt=\"\" class=\"wp-image-11085\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192418\/9-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192418\/9-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192418\/9-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192418\/9-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffda76\"><strong>slash : \/ (\ube57\uae08)<\/strong><\/p>\n\n\n\n<p><strong>slash<\/strong>\ub294 '\uc0ac\uc120\uc73c\ub85c \uc904\uc744 \uae0b\ub294\ub2e4'\ub294 \ub73b\uc744 \uac00\uc9d1\ub2c8\ub2e4.<br>\ub530\ub77c\uc11c \uae00\uc758 \ub0b4\uc6a9\uc744 \ubd84\ub9ac\uc2dc\ud0a4\ub294 \ube57\uae08\uc744 <strong>slash<\/strong>\ub77c\uace0 \ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192424\/10-1.jpg\" alt=\"\" class=\"wp-image-11086\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192424\/10-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192424\/10-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192424\/10-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192424\/10-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p><em>For lunch, you can choose between chicken \/ fish.<br>\uc810\uc2ec\uc73c\ub85c \ub2ed\uace0\uae30 \ub610\ub294 \uc0dd\uc120 \uc694\ub9ac\ub97c \uc120\ud0dd\ud560 \uc218 \uc788\ub2e4.<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192432\/11-1.jpg\" alt=\"\" class=\"wp-image-11087\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192432\/11-1.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192432\/11-1-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192432\/11-1-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192432\/11-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffda76\"><strong>table \/ chart<\/strong> : <strong>\u203b (\ucc38\uace0\ud45c)<\/strong><\/p>\n\n\n\n<p>\uc5b4\ub5a4 \ub0b4\uc6a9\uc744 \uc2dc\uac01\uc801\uc73c\ub85c \ub354 \uc27d\uac8c \ub098\ud0c0\ub0b8 \ud45c\ub97c <strong>table<\/strong> \ub610\ub294 <strong>chart<\/strong>\ub77c\uace0 \ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192439\/12.jpg\" alt=\"\" class=\"wp-image-11088\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192439\/12.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192439\/12-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192439\/12-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192439\/12-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p><em>You can refer to the table below for a refund notice.<br>\ud658\ubd88 \uc548\ub0b4\ub294 \uc544\ub798\uc5d0 \uc788\ub294 \ucc38\uace0\ud45c\ub97c \ubcf4\uc2dc\uba74 \ub429\ub2c8\ub2e4.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>\ub290\ub08c\ud45c\ub97c \ud3ec\ud568\ud574 \uc628\uc810, \uad04\ud638 \ub4f1 <strong>\ud2b9\uc218\uae30\ud638\ub97c \uc601\uc5b4\ub85c<\/strong> \uc5b4\ub5bb\uac8c \ub9d0\ud558\ub294 \uc9c0 \ud568\uaed8 \uc54c\uc544\ubcf4\uc558\uc2b5\ub2c8\ub2e4!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/engoo.co.kr\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192620\/2.png\" alt=\"\" class=\"wp-image-11089\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192620\/2.png 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192620\/2-300x300.png 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192620\/2-150x150.png 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192620\/2-768x768.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>\uc0c1\ub2e8\uc758 \uc774\ubbf8\uc9c0\ub97c \ud074\ub9ad\ud574 \uc9c0\uae08 \ubc14\ub85c <strong>\uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4<\/strong>\ub97c \ub9cc\ub098\ubcf4\uc138\uc694!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/engoo.co.kr\/blog\/%eb%93%9c%eb%94%94%ec%96%b4-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%8b%9d%ec%83%81%ed%95%9c-finally%eb%8a%94-%ec%9d%b4%ec%a0%9c-%ea%b7%b8%eb%a7%8c\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192641\/0-3.jpg\" alt=\"\" class=\"wp-image-11090\" srcset=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192641\/0-3.jpg 900w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192641\/0-3-300x300.jpg 300w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192641\/0-3-150x150.jpg 150w, https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192641\/0-3-768x768.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>'<strong>\ub4dc\ub514\uc5b4<\/strong>'\ub294 \uc601\uc5b4\ub85c?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.youtube.com\/channel\/UCdAc7q4b6u7llhYglqDcf6Q\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192657\/%EC%9B%90%EC%A0%95%EB%8C%801.png\" alt=\"\" class=\"wp-image-11091\"\/><\/a><\/figure><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\uc548\ub155\ud558\uc138\uc694. \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4\uc785\ub2c8\ub2e4. \u2018\ub290\ub08c\ud45c\u2019\ub294 \uc601\uc5b4\ub85c \uc5b4\ub5bb\uac8c \ub9d0\ud560\uae4c\uc694? \uc624\ub298\uc740 \uac01\uc885 \ud2b9\uc218\ubb38\uc790(!?&amp;\u203b\/) \ub97c \uc601\uc5b4\ub85c \uc5b4\ub5bb\uac8c \ud45c\ud604\ud558\ub294\uc9c0 \ud568\uaed8 \uc54c\uc544\ubcf4\ub3c4\ub85d \ud558\uaca0\uc2b5\ub2c8\ub2e4! period \/ full stop\u00a0: . (\ub9c8\uce68\ud45c\/\uc628\uc810) period\ub294 \uc5b4\ub5a4 \uc77c\uc774\ub098 \uc0ac\uac74\uc758 \ub9c8\uc9c0\ub9c9\uc744 \uc758\ubbf8\ud558\uae30 \ub54c\ubb38\uc5d0 \ubb38\uc7a5\uc744 \ub05d\ub0b4\ub294 \ub9c8\uce68\ud45c\ub97c period\ub77c\uace0 \ud569\ub2c8\ub2e4.\ube44\uc2b7\ud558\uac8c...<\/p>\n","protected":false},"author":427,"featured_media":11093,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ep_exclude_from_search":false,"unified_meta_tagline_field":"","footnotes":""},"categories":[1],"tags":[1258,2045,2048,2050,2044,2049,2046,2039,2040,2034,2037,2035,2038,1735,340,364,1913,1874,457,449,435,99,1212,1329,1161,13,180,230,217,575,2036,1007,514,570,246,1211,1179,1126,244,1175,740,584,289,10,488,923,493,175,341,263,392,518,2041,2043,2042,9,486,532,917,487,456,174,337,264],"class_list":["post-11075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3-","tag-1258","tag-bracket","tag-exclamationmark","tag-fullstop","tag-parenthesis","tag-period","tag-questionmark","tag-slash","tag-2040","tag-2034","tag-2037","tag-2035","tag-2038","tag-1735","tag-340","tag-364","tag-1913","tag-1874","tag-457","tag-449","tag-435","tag-99","tag-1212","tag-1329","tag-1161","tag-13","tag-180","tag-230","tag-217","tag-575","tag-2036","tag-1007","tag-514","tag-570","tag-246","tag-1211","tag-1179","tag-1126","tag-244","tag-1175","tag-740","tag-584","tag-289","tag-10","tag-488","tag-923","tag-493","tag-175","tag-341","tag-263","tag-392","tag-518","tag-2041","tag-2043","tag-2042","tag-9","tag-486","tag-532","tag-917","tag-487","tag-456","tag-174","tag-337","tag-264"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b) | Engoo \ube14\ub85c\uadf8<\/title>\n<meta name=\"description\" content=\"\ubb3c\uc74c\ud45c, \ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \ub2e4\uc591\ud55c \ud2b9\uc218\uae30\ud638\ub294 \uc601\uc5b4\ub85c \uc5b4\ub5bb\uac8c \ub9d0\ud560\uae4c?? \uc9c0\uae08 \ubc14\ub85c \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4\uc5d0\uc11c \ud655\uc778\ud558\uc138\uc694! \uc6d0\uc5b4\ubbfc \ud654\uc0c1\uc601\uc5b4, \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4!!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/engoo.co.kr\/blog\/3\ubd84-\uc601\uc5b4\ud68c\ud654\/\ub290\ub08c\ud45c-\uc601\uc5b4\ub85c-\uc601\uc5b4\ub85c-\ub9d0\ud574\ubcf4\ub294-\ud2b9\uc218\uae30\ud638-\u203b\/\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b) | Engoo \ube14\ub85c\uadf8\" \/>\n<meta property=\"og:description\" content=\"\ubb3c\uc74c\ud45c, \ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \ub2e4\uc591\ud55c \ud2b9\uc218\uae30\ud638\ub294 \uc601\uc5b4\ub85c \uc5b4\ub5bb\uac8c \ub9d0\ud560\uae4c?? \uc9c0\uae08 \ubc14\ub85c \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4\uc5d0\uc11c \ud655\uc778\ud558\uc138\uc694! \uc6d0\uc5b4\ubbfc \ud654\uc0c1\uc601\uc5b4, \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4!!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/engoo.co.kr\/blog\/3\ubd84-\uc601\uc5b4\ud68c\ud654\/\ub290\ub08c\ud45c-\uc601\uc5b4\ub85c-\uc601\uc5b4\ub85c-\ub9d0\ud574\ubcf4\ub294-\ud2b9\uc218\uae30\ud638-\u203b\/\" \/>\n<meta property=\"og:site_name\" content=\"Engoo \ube14\ub85c\uadf8\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-07T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-05T01:43:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192833\/%EB%8A%90%EB%82%8C%ED%91%9C-back-image-%EB%B3%B5%EC%82%AC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Engoo Korea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\uae00\uc4f4\uc774\" \/>\n\t<meta name=\"twitter:data1\" content=\"Engoo Korea\" \/>\n\t<meta name=\"twitter:label2\" content=\"\uc608\uc0c1 \ub418\ub294 \ud310\ub3c5 \uc2dc\uac04\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\ubd84\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/\"},\"author\":{\"name\":\"Engoo Korea\",\"@id\":\"https:\/\/engoo.co.kr\/blog\/#\/schema\/person\/1ead6a8f55de9a298d287b2b73541112\"},\"headline\":\"\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b)\",\"datePublished\":\"2022-02-07T00:00:00+00:00\",\"dateModified\":\"2022-08-05T01:43:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\/\/engoo.co.kr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192833\/%EB%8A%90%EB%82%8C%ED%91%9C-back-image-%EB%B3%B5%EC%82%AC.jpg\",\"keywords\":[\"#\uc5d4\uad6c\uc804\ud654\uc601\uc5b4\",\"bracket\",\"exclamationmark\",\"fullstop\",\"parenthesis\",\"period\",\"questionmark\",\"slash\",\"\uad04\ud638\uc601\uc5b4\ub85c\",\"\ub290\ub08c\ud45c\uc601\uc5b4\ub85c\",\"\ub9c8\uce68\ud45c\uc601\uc5b4\ub85c\",\"\ubb3c\uc74c\ud45c\uc601\uc5b4\ub85c\",\"\ube57\uae08\uc601\uc5b4\ub85c\",\"\uc131\uc778\uae30\ucd08\uc601\uc5b4\",\"\uc131\uc778\ud654\uc0c1\uc601\uc5b4\",\"\uc5b4\ub9b0\uc774\uc601\uc5b4\",\"\uc5b4\ub9b0\uc774\uc601\uc5b4\uac15\uc0ac\",\"\uc5b4\ub9b0\uc774\uc601\uc5b4\uacf5\ubd80\",\"\uc5b4\ub9b0\uc774\uc601\uc5b4\ud68c\ud654\",\"\uc5b4\ub9b0\uc774\uc804\ud654\uc601\uc5b4\",\"\uc5b4\ub9b0\uc774\ud654\uc0c1\uc601\uc5b4\",\"\uc5d4\uad6c\ud654\uc0c1\uc601\uc5b4\",\"\uc5d4\uad6c\ud654\uc0c1\uc601\uc5b4\uc0ac\uc774\ud2b8\",\"\uc5d4\uad6c\ud654\uc0c1\uc601\uc5b4\ucd94\ucc9c\",\"\uc5d4\uad6c\ud654\uc0c1\uc601\uc5b4\ud6c4\uae30\",\"\uc601\uc5b4\ud68c\ud654\",\"\uc601\uc5b4\ud68c\ud654\uacf5\ubd80\",\"\uc601\uc5b4\ud68c\ud654\uacfc\uc678\",\"\uc601\uc5b4\ud68c\ud654\ub3c5\ud559\",\"\uc601\uc5b4\ud68c\ud654\ud6c4\uae30\",\"\uc628\uc810\uc601\uc5b4\ub85c\",\"\uc678\uad6d\uc778\uce5c\uad6c\",\"\uc678\uad6d\uc778\uce5c\uad6c\uc0ac\uadc0\uae30\",\"\uc6d0\uc5b4\ubbfc\uac15\uc0ac\",\"\uc6d0\uc5b4\ubbfc\uc601\uc5b4\",\"\uc6d0\uc5b4\ubbfc\uc601\uc5b4\uacf5\ubd80\",\"\uc6d0\uc5b4\ubbfc\uc601\uc5b4\ub300\ud654\",\"\uc6d0\uc5b4\ubbfc\uc601\uc5b4\ud45c\ud604\",\"\uc6d0\uc5b4\ubbfc\uc601\uc5b4\ud68c\ud654\",\"\uc6d0\uc5b4\ubbfc\uc601\uc5b4\ud68c\ud654\ud45c\ud604\",\"\uc6d0\uc5b4\ubbfc\uc804\ud654\uc601\uc5b4\",\"\uc6d0\uc5b4\ubbfc\ud29c\ud130\",\"\uc6d0\uc5b4\ubbfc\ud654\uc0c1\uc601\uc5b4\",\"\uc804\ud654\uc601\uc5b4\",\"\uc804\ud654\uc601\uc5b4\uac00\uaca9\",\"\uc804\ud654\uc601\uc5b4\ub3c5\ud559\",\"\uc804\ud654\uc601\uc5b4\uc0ac\uc774\ud2b8\",\"\uc804\ud654\uc601\uc5b4\ucd94\ucc9c\",\"\uc804\ud654\uc601\uc5b4\ud68c\ud654\",\"\uc804\ud654\uc601\uc5b4\ud6c4\uae30\",\"\ucd08\ub4f1\ud654\uc0c1\uc601\uc5b4\",\"\ucd08\ubcf4\ud654\uc0c1\uc601\uc5b4\",\"\ud2b9\uc218\ubb38\uc790\",\"\ud2b9\uc218\ubb38\uc790\uc601\uc5b4\",\"\ud2b9\uc218\ubb38\uc790\uc601\uc5b4\ub85c\",\"\ud654\uc0c1\uc601\uc5b4\",\"\ud654\uc0c1\uc601\uc5b4\uac00\uaca9\",\"\ud654\uc0c1\uc601\uc5b4\uacf5\ubd80\",\"\ud654\uc0c1\uc601\uc5b4\uacf5\ubd80\ubc95\",\"\ud654\uc0c1\uc601\uc5b4\ube44\uad50\",\"\ud654\uc0c1\uc601\uc5b4\uc0ac\uc774\ud2b8\",\"\ud654\uc0c1\uc601\uc5b4\ucd94\ucc9c\",\"\ud654\uc0c1\uc601\uc5b4\ud68c\ud654\",\"\ud654\uc0c1\uc601\uc5b4\ud6c4\uae30\"],\"articleSection\":[\"3\ubd84 \uc601\uc5b4\ud68c\ud654\"],\"inLanguage\":\"ko-KR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/\",\"url\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/\",\"name\":\"\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b) | Engoo \ube14\ub85c\uadf8\",\"isPartOf\":{\"@id\":\"https:\/\/engoo.co.kr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192833\/%EB%8A%90%EB%82%8C%ED%91%9C-back-image-%EB%B3%B5%EC%82%AC.jpg\",\"datePublished\":\"2022-02-07T00:00:00+00:00\",\"dateModified\":\"2022-08-05T01:43:57+00:00\",\"description\":\"\ubb3c\uc74c\ud45c, \ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \ub2e4\uc591\ud55c \ud2b9\uc218\uae30\ud638\ub294 \uc601\uc5b4\ub85c \uc5b4\ub5bb\uac8c \ub9d0\ud560\uae4c?? \uc9c0\uae08 \ubc14\ub85c \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4\uc5d0\uc11c \ud655\uc778\ud558\uc138\uc694! \uc6d0\uc5b4\ubbfc \ud654\uc0c1\uc601\uc5b4, \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4!!\",\"breadcrumb\":{\"@id\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#breadcrumb\"},\"inLanguage\":\"ko-KR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#primaryimage\",\"url\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192833\/%EB%8A%90%EB%82%8C%ED%91%9C-back-image-%EB%B3%B5%EC%82%AC.jpg\",\"contentUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192833\/%EB%8A%90%EB%82%8C%ED%91%9C-back-image-%EB%B3%B5%EC%82%AC.jpg\",\"width\":700,\"height\":467,\"caption\":\"set of color paper alphabet punctuation mark\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Engoo\",\"item\":\"https:\/\/engoo.co.kr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ube14\ub85c\uadf8\",\"item\":\"https:\/\/engoo.co.kr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"3\ubd84 \uc601\uc5b4\ud68c\ud654\",\"item\":\"https:\/\/engoo.co.kr\/blog\/category\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/engoo.co.kr\/blog\/#website\",\"url\":\"https:\/\/engoo.co.kr\/blog\/\",\"name\":\"Engoo \ube14\ub85c\uadf8\",\"description\":\"\uc6d0\uc5b4\ubbfc \uc601\uc5b4\ud68c\ud654 \uc601\uc5b4\uacf5\ubd80\ub97c \uc704\ud55c \ubb34\ub8cc \ud559\uc2b5 \uc790\ub8cc\",\"publisher\":{\"@id\":\"https:\/\/engoo.co.kr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/engoo.co.kr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ko-KR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/engoo.co.kr\/blog\/#organization\",\"name\":\"Engoo \ube14\ub85c\uadf8\",\"url\":\"https:\/\/engoo.co.kr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\/\/engoo.co.kr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2018\/08\/15023043\/engoo-logo.svg\",\"contentUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2018\/08\/15023043\/engoo-logo.svg\",\"caption\":\"Engoo \ube14\ub85c\uadf8\"},\"image\":{\"@id\":\"https:\/\/engoo.co.kr\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/engoo.co.kr\/blog\/#\/schema\/person\/1ead6a8f55de9a298d287b2b73541112\",\"name\":\"Engoo Korea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\/\/engoo.co.kr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/engoo.co.kr\/blog\/wp-content\/uploads\/sites\/2\/2022\/09\/cropped-Engoo_logo_Profile-96x96.png\",\"contentUrl\":\"https:\/\/engoo.co.kr\/blog\/wp-content\/uploads\/sites\/2\/2022\/09\/cropped-Engoo_logo_Profile-96x96.png\",\"caption\":\"Engoo Korea\"},\"url\":\"https:\/\/engoo.co.kr\/blog\/author\/jihyeohk\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b) | Engoo \ube14\ub85c\uadf8","description":"\ubb3c\uc74c\ud45c, \ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \ub2e4\uc591\ud55c \ud2b9\uc218\uae30\ud638\ub294 \uc601\uc5b4\ub85c \uc5b4\ub5bb\uac8c \ub9d0\ud560\uae4c?? \uc9c0\uae08 \ubc14\ub85c \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4\uc5d0\uc11c \ud655\uc778\ud558\uc138\uc694! \uc6d0\uc5b4\ubbfc \ud654\uc0c1\uc601\uc5b4, \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4!!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/engoo.co.kr\/blog\/3\ubd84-\uc601\uc5b4\ud68c\ud654\/\ub290\ub08c\ud45c-\uc601\uc5b4\ub85c-\uc601\uc5b4\ub85c-\ub9d0\ud574\ubcf4\ub294-\ud2b9\uc218\uae30\ud638-\u203b\/","og_locale":"ko_KR","og_type":"article","og_title":"\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b) | Engoo \ube14\ub85c\uadf8","og_description":"\ubb3c\uc74c\ud45c, \ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \ub2e4\uc591\ud55c \ud2b9\uc218\uae30\ud638\ub294 \uc601\uc5b4\ub85c \uc5b4\ub5bb\uac8c \ub9d0\ud560\uae4c?? \uc9c0\uae08 \ubc14\ub85c \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4\uc5d0\uc11c \ud655\uc778\ud558\uc138\uc694! \uc6d0\uc5b4\ubbfc \ud654\uc0c1\uc601\uc5b4, \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4!!","og_url":"https:\/\/engoo.co.kr\/blog\/3\ubd84-\uc601\uc5b4\ud68c\ud654\/\ub290\ub08c\ud45c-\uc601\uc5b4\ub85c-\uc601\uc5b4\ub85c-\ub9d0\ud574\ubcf4\ub294-\ud2b9\uc218\uae30\ud638-\u203b\/","og_site_name":"Engoo \ube14\ub85c\uadf8","article_published_time":"2022-02-07T00:00:00+00:00","article_modified_time":"2022-08-05T01:43:57+00:00","og_image":[{"width":700,"height":467,"url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192833\/%EB%8A%90%EB%82%8C%ED%91%9C-back-image-%EB%B3%B5%EC%82%AC.jpg","type":"image\/jpeg"}],"author":"Engoo Korea","twitter_card":"summary_large_image","twitter_misc":{"\uae00\uc4f4\uc774":"Engoo Korea","\uc608\uc0c1 \ub418\ub294 \ud310\ub3c5 \uc2dc\uac04":"1\ubd84"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#article","isPartOf":{"@id":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/"},"author":{"name":"Engoo Korea","@id":"https:\/\/engoo.co.kr\/blog\/#\/schema\/person\/1ead6a8f55de9a298d287b2b73541112"},"headline":"\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b)","datePublished":"2022-02-07T00:00:00+00:00","dateModified":"2022-08-05T01:43:57+00:00","mainEntityOfPage":{"@id":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/"},"wordCount":92,"publisher":{"@id":"https:\/\/engoo.co.kr\/blog\/#organization"},"image":{"@id":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192833\/%EB%8A%90%EB%82%8C%ED%91%9C-back-image-%EB%B3%B5%EC%82%AC.jpg","keywords":["#\uc5d4\uad6c\uc804\ud654\uc601\uc5b4","bracket","exclamationmark","fullstop","parenthesis","period","questionmark","slash","\uad04\ud638\uc601\uc5b4\ub85c","\ub290\ub08c\ud45c\uc601\uc5b4\ub85c","\ub9c8\uce68\ud45c\uc601\uc5b4\ub85c","\ubb3c\uc74c\ud45c\uc601\uc5b4\ub85c","\ube57\uae08\uc601\uc5b4\ub85c","\uc131\uc778\uae30\ucd08\uc601\uc5b4","\uc131\uc778\ud654\uc0c1\uc601\uc5b4","\uc5b4\ub9b0\uc774\uc601\uc5b4","\uc5b4\ub9b0\uc774\uc601\uc5b4\uac15\uc0ac","\uc5b4\ub9b0\uc774\uc601\uc5b4\uacf5\ubd80","\uc5b4\ub9b0\uc774\uc601\uc5b4\ud68c\ud654","\uc5b4\ub9b0\uc774\uc804\ud654\uc601\uc5b4","\uc5b4\ub9b0\uc774\ud654\uc0c1\uc601\uc5b4","\uc5d4\uad6c\ud654\uc0c1\uc601\uc5b4","\uc5d4\uad6c\ud654\uc0c1\uc601\uc5b4\uc0ac\uc774\ud2b8","\uc5d4\uad6c\ud654\uc0c1\uc601\uc5b4\ucd94\ucc9c","\uc5d4\uad6c\ud654\uc0c1\uc601\uc5b4\ud6c4\uae30","\uc601\uc5b4\ud68c\ud654","\uc601\uc5b4\ud68c\ud654\uacf5\ubd80","\uc601\uc5b4\ud68c\ud654\uacfc\uc678","\uc601\uc5b4\ud68c\ud654\ub3c5\ud559","\uc601\uc5b4\ud68c\ud654\ud6c4\uae30","\uc628\uc810\uc601\uc5b4\ub85c","\uc678\uad6d\uc778\uce5c\uad6c","\uc678\uad6d\uc778\uce5c\uad6c\uc0ac\uadc0\uae30","\uc6d0\uc5b4\ubbfc\uac15\uc0ac","\uc6d0\uc5b4\ubbfc\uc601\uc5b4","\uc6d0\uc5b4\ubbfc\uc601\uc5b4\uacf5\ubd80","\uc6d0\uc5b4\ubbfc\uc601\uc5b4\ub300\ud654","\uc6d0\uc5b4\ubbfc\uc601\uc5b4\ud45c\ud604","\uc6d0\uc5b4\ubbfc\uc601\uc5b4\ud68c\ud654","\uc6d0\uc5b4\ubbfc\uc601\uc5b4\ud68c\ud654\ud45c\ud604","\uc6d0\uc5b4\ubbfc\uc804\ud654\uc601\uc5b4","\uc6d0\uc5b4\ubbfc\ud29c\ud130","\uc6d0\uc5b4\ubbfc\ud654\uc0c1\uc601\uc5b4","\uc804\ud654\uc601\uc5b4","\uc804\ud654\uc601\uc5b4\uac00\uaca9","\uc804\ud654\uc601\uc5b4\ub3c5\ud559","\uc804\ud654\uc601\uc5b4\uc0ac\uc774\ud2b8","\uc804\ud654\uc601\uc5b4\ucd94\ucc9c","\uc804\ud654\uc601\uc5b4\ud68c\ud654","\uc804\ud654\uc601\uc5b4\ud6c4\uae30","\ucd08\ub4f1\ud654\uc0c1\uc601\uc5b4","\ucd08\ubcf4\ud654\uc0c1\uc601\uc5b4","\ud2b9\uc218\ubb38\uc790","\ud2b9\uc218\ubb38\uc790\uc601\uc5b4","\ud2b9\uc218\ubb38\uc790\uc601\uc5b4\ub85c","\ud654\uc0c1\uc601\uc5b4","\ud654\uc0c1\uc601\uc5b4\uac00\uaca9","\ud654\uc0c1\uc601\uc5b4\uacf5\ubd80","\ud654\uc0c1\uc601\uc5b4\uacf5\ubd80\ubc95","\ud654\uc0c1\uc601\uc5b4\ube44\uad50","\ud654\uc0c1\uc601\uc5b4\uc0ac\uc774\ud2b8","\ud654\uc0c1\uc601\uc5b4\ucd94\ucc9c","\ud654\uc0c1\uc601\uc5b4\ud68c\ud654","\ud654\uc0c1\uc601\uc5b4\ud6c4\uae30"],"articleSection":["3\ubd84 \uc601\uc5b4\ud68c\ud654"],"inLanguage":"ko-KR"},{"@type":"WebPage","@id":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/","url":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/","name":"\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b) | Engoo \ube14\ub85c\uadf8","isPartOf":{"@id":"https:\/\/engoo.co.kr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#primaryimage"},"image":{"@id":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192833\/%EB%8A%90%EB%82%8C%ED%91%9C-back-image-%EB%B3%B5%EC%82%AC.jpg","datePublished":"2022-02-07T00:00:00+00:00","dateModified":"2022-08-05T01:43:57+00:00","description":"\ubb3c\uc74c\ud45c, \ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \ub2e4\uc591\ud55c \ud2b9\uc218\uae30\ud638\ub294 \uc601\uc5b4\ub85c \uc5b4\ub5bb\uac8c \ub9d0\ud560\uae4c?? \uc9c0\uae08 \ubc14\ub85c \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4\uc5d0\uc11c \ud655\uc778\ud558\uc138\uc694! \uc6d0\uc5b4\ubbfc \ud654\uc0c1\uc601\uc5b4, \uc5d4\uad6c \ud654\uc0c1\uc601\uc5b4!!","breadcrumb":{"@id":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#breadcrumb"},"inLanguage":"ko-KR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/"]}]},{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#primaryimage","url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192833\/%EB%8A%90%EB%82%8C%ED%91%9C-back-image-%EB%B3%B5%EC%82%AC.jpg","contentUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2022\/02\/06192833\/%EB%8A%90%EB%82%8C%ED%91%9C-back-image-%EB%B3%B5%EC%82%AC.jpg","width":700,"height":467,"caption":"set of color paper alphabet punctuation mark"},{"@type":"BreadcrumbList","@id":"https:\/\/engoo.co.kr\/blog\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/%eb%8a%90%eb%82%8c%ed%91%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%ec%98%81%ec%96%b4%eb%a1%9c-%eb%a7%90%ed%95%b4%eb%b3%b4%eb%8a%94-%ed%8a%b9%ec%88%98%ea%b8%b0%ed%98%b8-%e2%80%bb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Engoo","item":"https:\/\/engoo.co.kr"},{"@type":"ListItem","position":2,"name":"\ube14\ub85c\uadf8","item":"https:\/\/engoo.co.kr\/blog\/"},{"@type":"ListItem","position":3,"name":"3\ubd84 \uc601\uc5b4\ud68c\ud654","item":"https:\/\/engoo.co.kr\/blog\/category\/3%eb%b6%84-%ec%98%81%ec%96%b4%ed%9a%8c%ed%99%94\/"},{"@type":"ListItem","position":4,"name":"\ub290\ub08c\ud45c \uc601\uc5b4\ub85c? \uc601\uc5b4\ub85c \ub9d0\ud574\ubcf4\ub294 \ud2b9\uc218\uae30\ud638(!, ?, \u203b)"}]},{"@type":"WebSite","@id":"https:\/\/engoo.co.kr\/blog\/#website","url":"https:\/\/engoo.co.kr\/blog\/","name":"Engoo \ube14\ub85c\uadf8","description":"\uc6d0\uc5b4\ubbfc \uc601\uc5b4\ud68c\ud654 \uc601\uc5b4\uacf5\ubd80\ub97c \uc704\ud55c \ubb34\ub8cc \ud559\uc2b5 \uc790\ub8cc","publisher":{"@id":"https:\/\/engoo.co.kr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/engoo.co.kr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ko-KR"},{"@type":"Organization","@id":"https:\/\/engoo.co.kr\/blog\/#organization","name":"Engoo \ube14\ub85c\uadf8","url":"https:\/\/engoo.co.kr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/engoo.co.kr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2018\/08\/15023043\/engoo-logo.svg","contentUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/2\/2018\/08\/15023043\/engoo-logo.svg","caption":"Engoo \ube14\ub85c\uadf8"},"image":{"@id":"https:\/\/engoo.co.kr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/engoo.co.kr\/blog\/#\/schema\/person\/1ead6a8f55de9a298d287b2b73541112","name":"Engoo Korea","image":{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/engoo.co.kr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/engoo.co.kr\/blog\/wp-content\/uploads\/sites\/2\/2022\/09\/cropped-Engoo_logo_Profile-96x96.png","contentUrl":"https:\/\/engoo.co.kr\/blog\/wp-content\/uploads\/sites\/2\/2022\/09\/cropped-Engoo_logo_Profile-96x96.png","caption":"Engoo Korea"},"url":"https:\/\/engoo.co.kr\/blog\/author\/jihyeohk\/"}]}},"_links":{"self":[{"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/posts\/11075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/users\/427"}],"replies":[{"embeddable":true,"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/comments?post=11075"}],"version-history":[{"count":7,"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/posts\/11075\/revisions"}],"predecessor-version":[{"id":11104,"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/posts\/11075\/revisions\/11104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/media\/11093"}],"wp:attachment":[{"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/media?parent=11075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/categories?post=11075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/engoo.co.kr\/blog\/wp-json\/wp\/v2\/tags?post=11075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}